{"id":59476,"date":"2025-07-18T12:16:22","date_gmt":"2025-07-18T10:16:22","guid":{"rendered":"https:\/\/cases.fundesplai.org\/experiencia\/puente-de-la-purisima-en-la-cinglera\/"},"modified":"2025-09-23T15:27:10","modified_gmt":"2025-09-23T13:27:10","slug":"puente-de-la-purisima-en-la-cinglera","status":"publish","type":"experiencia","link":"https:\/\/cases.fundesplai.org\/es\/experiencia\/puente-de-la-purisima-en-la-cinglera\/","title":{"rendered":"Puente de la Pur\u00edsima en La Cinglera"},"featured_media":59403,"template":"","comarca":[546],"oferta_especial":[560],"class_list":["post-59476","experiencia","type-experiencia","status-publish","has-post-thumbnail","hentry","comarca-osona","oferta_especial-con-actividades"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Puente de la Pur\u00edsima en La Cinglera - Cases de col\u00f2nies - Fundesplai<\/title>\n<meta name=\"description\" content=\"Ven a buscar el ti\u00f3 por el puente de la Pur\u00edsima en la casa de colonias La Cinglera. Incluye pensi\u00f3n completa y actividades familiares.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puente de la Pur\u00edsima en La Cinglera - Cases de col\u00f2nies - Fundesplai\" \/>\n<meta property=\"og:description\" content=\"Ven a buscar el ti\u00f3 por el puente de la Pur\u00edsima en la casa de colonias La Cinglera. Incluye pensi\u00f3n completa y actividades familiares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cases.fundesplai.org\/es\/experiencia\/puente-de-la-purisima-en-la-cinglera\/\" \/>\n<meta property=\"og:site_name\" content=\"Cases de col\u00f2nies - Fundesplai\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-23T13:27:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/07\/Excursio-nens-Purissima-Fundesplai.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/experiencia\\\/puente-de-la-purisima-en-la-cinglera\\\/\",\"url\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/experiencia\\\/puente-de-la-purisima-en-la-cinglera\\\/\",\"name\":\"Puente de la Pur\u00edsima en La Cinglera - Cases de col\u00f2nies - Fundesplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/experiencia\\\/puente-de-la-purisima-en-la-cinglera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/experiencia\\\/puente-de-la-purisima-en-la-cinglera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cases.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Excursio-nens-Purissima-Fundesplai.webp\",\"datePublished\":\"2025-07-18T10:16:22+00:00\",\"dateModified\":\"2025-09-23T13:27:10+00:00\",\"description\":\"Ven a buscar el ti\u00f3 por el puente de la Pur\u00edsima en la casa de colonias La Cinglera. Incluye pensi\u00f3n completa y actividades familiares.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/experiencia\\\/puente-de-la-purisima-en-la-cinglera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/experiencia\\\/puente-de-la-purisima-en-la-cinglera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/experiencia\\\/puente-de-la-purisima-en-la-cinglera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cases.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Excursio-nens-Purissima-Fundesplai.webp\",\"contentUrl\":\"https:\\\/\\\/cases.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Excursio-nens-Purissima-Fundesplai.webp\",\"width\":1888,\"height\":900,\"caption\":\"Infants d'excursi\u00f3 pel bosc\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/experiencia\\\/puente-de-la-purisima-en-la-cinglera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/inici-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puente de la Pur\u00edsima en La Cinglera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/\",\"name\":\"Cases de col\u00f2nies - Fundesplai\",\"description\":\"Equipaments de Fundesplai\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puente de la Pur\u00edsima en La Cinglera - Cases de col\u00f2nies - Fundesplai","description":"Ven a buscar el ti\u00f3 por el puente de la Pur\u00edsima en la casa de colonias La Cinglera. Incluye pensi\u00f3n completa y actividades familiares.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Puente de la Pur\u00edsima en La Cinglera - Cases de col\u00f2nies - Fundesplai","og_description":"Ven a buscar el ti\u00f3 por el puente de la Pur\u00edsima en la casa de colonias La Cinglera. Incluye pensi\u00f3n completa y actividades familiares.","og_url":"https:\/\/cases.fundesplai.org\/es\/experiencia\/puente-de-la-purisima-en-la-cinglera\/","og_site_name":"Cases de col\u00f2nies - Fundesplai","article_modified_time":"2025-09-23T13:27:10+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/07\/Excursio-nens-Purissima-Fundesplai.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cases.fundesplai.org\/es\/experiencia\/puente-de-la-purisima-en-la-cinglera\/","url":"https:\/\/cases.fundesplai.org\/es\/experiencia\/puente-de-la-purisima-en-la-cinglera\/","name":"Puente de la Pur\u00edsima en La Cinglera - Cases de col\u00f2nies - Fundesplai","isPartOf":{"@id":"https:\/\/cases.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cases.fundesplai.org\/es\/experiencia\/puente-de-la-purisima-en-la-cinglera\/#primaryimage"},"image":{"@id":"https:\/\/cases.fundesplai.org\/es\/experiencia\/puente-de-la-purisima-en-la-cinglera\/#primaryimage"},"thumbnailUrl":"https:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/07\/Excursio-nens-Purissima-Fundesplai.webp","datePublished":"2025-07-18T10:16:22+00:00","dateModified":"2025-09-23T13:27:10+00:00","description":"Ven a buscar el ti\u00f3 por el puente de la Pur\u00edsima en la casa de colonias La Cinglera. Incluye pensi\u00f3n completa y actividades familiares.","breadcrumb":{"@id":"https:\/\/cases.fundesplai.org\/es\/experiencia\/puente-de-la-purisima-en-la-cinglera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cases.fundesplai.org\/es\/experiencia\/puente-de-la-purisima-en-la-cinglera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cases.fundesplai.org\/es\/experiencia\/puente-de-la-purisima-en-la-cinglera\/#primaryimage","url":"https:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/07\/Excursio-nens-Purissima-Fundesplai.webp","contentUrl":"https:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/07\/Excursio-nens-Purissima-Fundesplai.webp","width":1888,"height":900,"caption":"Infants d'excursi\u00f3 pel bosc"},{"@type":"BreadcrumbList","@id":"https:\/\/cases.fundesplai.org\/es\/experiencia\/puente-de-la-purisima-en-la-cinglera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/cases.fundesplai.org\/es\/inici-2\/"},{"@type":"ListItem","position":2,"name":"Puente de la Pur\u00edsima en La Cinglera"}]},{"@type":"WebSite","@id":"https:\/\/cases.fundesplai.org\/es\/#website","url":"https:\/\/cases.fundesplai.org\/es\/","name":"Cases de col\u00f2nies - Fundesplai","description":"Equipaments de Fundesplai","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cases.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/experiencia\/59476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/experiencia"}],"about":[{"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/experiencia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/59403"}],"wp:attachment":[{"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=59476"}],"wp:term":[{"taxonomy":"comarca","embeddable":true,"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/comarca?post=59476"},{"taxonomy":"oferta_especial","embeddable":true,"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/oferta_especial?post=59476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}