{"id":59860,"date":"2025-09-12T16:39:53","date_gmt":"2025-09-12T14:39:53","guid":{"rendered":"https:\/\/cases.fundesplai.org\/blog-es\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/"},"modified":"2025-09-15T12:36:20","modified_gmt":"2025-09-15T10:36:20","slug":"como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias","status":"publish","type":"post","link":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/","title":{"rendered":"C\u00f3mo reducimos el desperdicio alimentario en las casas de colonias"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbIntro\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Cada <strong>29 de septiembre<\/strong> se celebra el <strong>D\u00eda Internacional contra el Desperdicio Alimentario<\/strong>. Una fecha que nos recuerda la magnitud de ese problema global y la responsabilidad que tenemos como sociedad para revertirlo. En Fundesplai lo sabemos bien, por eso <strong>la reducci\u00f3n del desperdicio alimentario en las casas de colonias es una de nuestras grandes prioridades<\/strong>.  <\/p>\n<p>Hablamos de equipamientos que cada a\u00f1o reciben miles de ni\u00f1os, ni\u00f1as, j\u00f3venes, adultos y familias en estancias de ocio en la naturaleza. Lo que significa <strong>miles de comidas y oportunidades para educar en positivo, y concienciar y sensibilizar a todo el mundo de la importancia de no tirar la comida<\/strong>, puesto que las cifras son alarmantes. <\/p>\n<p>Por eso, dentro de la propuesta educativa <a href=\"https:\/\/fundesplai.org\/mcm\/\">\u201cMenjar canvia el m\u00f3n\u201d<\/a>, y bajo el lema <strong>\u201cSTOP Desperdiciar Comida\u201d<\/strong>, llevamos a cabo <strong>una iniciativa espec\u00edfica para trabajar el desperdicio alimentario en nuestras casas de colonias, albergues y terrenos de acampada<\/strong>.<\/p>\n<p>Y para darle forma, hemos creado una <strong>gu\u00eda pr\u00e1ctica con acciones, actividades, reflexiones, datos y recursos<\/strong> para transformar las vivencias en estos espacios en una oportunidad para aprender, actuar y construir un futuro m\u00e1s sostenible.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/09\/Guia-educativa-cases-de-colonies-malbaratament-alimentari.pdf\u00bb button_text=\u00bbConsulta aqu\u00ed la gu\u00eda para la reducci\u00f3n del desperdicio\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||35px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_divider _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||35px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text admin_label=\u00bbCases de col\u00f2nies\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Las casas de colonias, un escenario educativo<\/h3>\n<p>Seg\u00fan <a href=\"http:\/\/chrome-extension:\/\/efaidnbmnnnibpcajpcglclefindmkaj\/https:\/\/www.fao.org\/4\/i2697s\/i2697s.pdf\" data-wplink-url-error=\"true\">un estudio de la FAO<\/a>, cada a\u00f1o se pierde <strong>un tercio de los alimentos<\/strong> que se producen en el mundo para el consumo humano. En Catalu\u00f1a, esto equivale a unos <strong>35 kg de comida por persona<\/strong> cada a\u00f1o. Algo que no solo tiene un enorme impacto social y \u00e9tico, sino tambi\u00e9n ambiental.  <\/p>\n<p>En los comedores de las casas de colonias y albergues, los y las participantes de las estancias descubren que <strong>alimentarse no es solo saciar el apetito<\/strong>. Es conectar con el planeta y con las personas, es entender que tirar comida tiene consecuencias muy reales y que cada mordisco tiene un peso. <\/p>\n<p>Este entorno de convivencia es ideal, pues, para <strong>trabajar la sostenibilidad de una manera vivencial y significativa<\/strong>. Es as\u00ed como estos espacios se convierten en un escenario educativo clave para acompa\u00f1ar a ni\u00f1os, ni\u00f1as y j\u00f3venes en el camino hacia un estilo de vida m\u00e1s consciente y sostenible. <\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbGuia: eina per transformar h\u00e0bits\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>La gu\u00eda: una herramienta para transformar h\u00e1bitos<\/h3>\n<p>Para hacer realidad este compromiso, hemos dise\u00f1ado la <strong>\u00abGu\u00eda educativa para reducir el desperdicio alimentario en las casas de colonias\u00bb<\/strong>. Un instrumento pr\u00e1ctico y participativo que busca <strong>implicar a ni\u00f1os, ni\u00f1as, j\u00f3venes, adultos y equipos educativos en la prevenci\u00f3n y reducci\u00f3n del desperdicio<\/strong>.  <\/p>\n<p>Encontrar\u00e1s <strong>orientaciones claras<\/strong> sobre c\u00f3mo organizar el espacio del comedor o las comidas para hacerlas m\u00e1s sostenibles; <strong>pasos concretos<\/strong> para separar, medir y reflexionar sobre los restos de comida; <strong>actividades y din\u00e1micas de sensibilizaci\u00f3n<\/strong> para promover la participaci\u00f3n activa de los ni\u00f1os, ni\u00f1as y j\u00f3venes; y <strong>recursos educativos<\/strong> para convertir los comedores en espacios de concienciaci\u00f3n y cambio. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bbon|on|off\u00bb admin_label=\u00bbPC\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||30px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/09\/Nenes-menjador-cases-colonies-Fundesplai.webp\u00bb title_text=\u00bbNi\u00f1as comedor casas colonias Fundesplai\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb|18px||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/09\/Malbaratament-alimentari-Fundesplai.webp\u00bb title_text=\u00bbDesperdicio alimentario Fundesplai\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb99.5%\u00bb min_height=\u00bb357.5px\u00bb custom_padding=\u00bb|||12px||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|on\u00bb admin_label=\u00bbMBL\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||20px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/09\/Nenes-menjador-cases-colonies-Fundesplai.webp\u00bb title_text=\u00bbNi\u00f1as comedor casas colonias Fundesplai\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||5px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/09\/Malbaratament-alimentari-Fundesplai.webp\u00bb title_text=\u00bbDesperdicio alimentario Fundesplai\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbCom ho fem?\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3 aria-level=\"2\">C\u00f3mo trabajamos la reducci\u00f3n del desperdicio alimentario<\/h3>\n<p>Lo trabajamos a partir de una <strong>metodolog\u00eda clara, participativa y educativa<\/strong> que involucra a ni\u00f1os, ni\u00f1as, j\u00f3venes, familias y equipos porque queremos que todo el mundo se sienta parte activa del proceso.<\/p>\n<ul>\n<li><strong>Sensibilizamos:<\/strong> hablamos sobre qu\u00e9 significa tirar comida y qu\u00e9 impacto tiene sobre el planeta y la sociedad. \u00a1Es el primer paso para tomar conciencia! <\/li>\n<li><strong>Jugamos:<\/strong> hacemos actividades l\u00fadicas, as\u00ed como juegos y v\u00eddeos interactivos adaptados a todas las edades para transformar acciones en cambios reales. La idea es incorporarlos a las estancias o plantearlos antes de ir. <\/li>\n<li><strong>Separamos y hacemos visible la comida que se tira:<\/strong> los restos se agrupan en comibles, incomibles y agua sobrante. As\u00ed, el derroche deja de ser un concepto abstracto y se convierte en una realidad tangible. <\/li>\n<li><strong>Cuantificamos:<\/strong> pesamos y registramos los datos para entender mejor la magnitud del desperdicio gracias a las auditor\u00edas.<\/li>\n<li><strong>Reflexionamos y actuamos:<\/strong> damos un papel activo a los j\u00f3venes y a los ni\u00f1os y ni\u00f1as para que propongan mejoras, asuman compromisos y descubran que estos h\u00e1bitos responsables son aplicables a las casas de colonias y tambi\u00e9n en casa.<\/li>\n<\/ul>\n<p>Las <strong>auditor\u00edas<\/strong> dise\u00f1adas por Fundesplai forman parte del proyecto global de prevenci\u00f3n del desperdicio alimentario en las instalaciones de naturaleza y conviven con las otras propuestas de ocio educativo que se desarrollan. As\u00ed, trabajamos <strong>valores como la convivencia, la responsabilidad ambiental y la conciencia alimentaria<\/strong>. <\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbInici\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>El inicio de un futuro m\u00e1s sostenible<\/h3>\n<p><span data-contrast=\"auto\">Como ves, <strong>el desperdicio alimentario es un problema de alcance global, pero tambi\u00e9n es un reto que podemos afrontar desde la proximidad<\/strong>. Y en las casas de colonias lo trabajamos todos los d\u00edas. Por eso, desde Fundesplai estamos convencidos de que <strong>cada mordisco cuenta, cada comida educa y cada gesto suma<\/strong>.   <\/span><\/p>\n<p><span data-contrast=\"auto\">Las casas de colonias no son s\u00f3lo un espacio de convivencia entre bosques, prados y monta\u00f1as: son un motor de cambio, una escuela de sostenibilidad y una oportunidad para tomar decisiones respetuosas con el medio ambiente. Te invitamos a venir a realizar una <a href=\"https:\/\/cases.fundesplai.org\/es\/servicios\/\">estancia de turismo rural familiar<\/a> y poner en pr\u00e1ctica todas estas medidas con los ni\u00f1os y ni\u00f1as. \u00bfTe animas? \ud83c\udf43 <\/span><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbEspai en blanc\u00bb module_id=\u00bbguia\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_text][et_pb_text disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbFormulari\u00bb _builder_version=\u00bb4.27.4&#8243; custom_margin=\u00bb35px||20px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb border_width_all=\u00bb3px\u00bb border_color_all=\u00bb#DCDC1C\u00bb disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4 style=\"text-align: center;\"><strong>Subscriu-te al nostre butllet\u00ed per rebre la Guia per a reduir el malbaratament alimentari a les Cases de Col\u00f2nies<\/strong><\/h4>\n<p><span class=\"ui-provider a b c d e f g h i j k l m n o p q r s t u v w x y z ab ac ae af ag ah ai aj ak\" dir=\"ltr\"><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_41' >\n                        <div class='gform_heading'>\n                            <p class='gform_description'><\/p>\n\t\t\t\t\t\t\t<p class='gform_required_legend'><\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_41'  action='\/es\/wp-json\/wp\/v2\/posts\/59860' data-formid='41' novalidate><div class='gf_invisible ginput_recaptchav3' data-sitekey='6LeSNbspAAAAANQgLUyAGs8szo9CXq4Lva9nl6pN' data-tabindex='0'><input id=\"input_eefeeecd1c0bcae5e450f8d8f1a25584\" class=\"gfield_recaptcha_response\" type=\"hidden\" name=\"input_eefeeecd1c0bcae5e450f8d8f1a25584\" value=\"\"\/><\/div>\n                        <div class='gform-body gform_body'><div id='gform_fields_41' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_41_9\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_41_9'>Instagram<\/label><div class='ginput_container'><input name='input_9' id='input_41_9' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_41_9'>Este campo es un campo de validaci\u00f3n y debe quedar sin cambios.<\/div><\/div><fieldset id=\"field_41_1\" class=\"gfield gfield--type-name gfield--input-type-name field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Nombre<\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_41_1'>\n                            \n                            <span id='input_41_1_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.3' id='input_41_1_3' value=''   aria-required='false'     \/>\n                                                    <label for='input_41_1_3' class='gform-field-label gform-field-label--type-sub '>Nombre<\/label>\n                                                <\/span>\n                            \n                            <span id='input_41_1_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.6' id='input_41_1_6' value=''   aria-required='false'     \/>\n                                                    <label for='input_41_1_6' class='gform-field-label gform-field-label--type-sub '>Apellidos<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_41_3\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_41_3'>Correo electr\u00f3nico<\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_3' id='input_41_3' type='email' value='' class='large'     aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_41_7\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_7' id='input_41_7' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='guia-malbaratament-alimentari-cases-colonies' \/><\/div><\/div><fieldset id=\"field_41_8\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield--input-type-checkbox gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Pol\u00edtica de privacitat<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_container ginput_container_checkbox'><div class='gfield_checkbox ' id='input_41_8'><div class='gchoice gchoice_41_8_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_8.1' type='checkbox'  value='politica-privacitat-ok'  id='choice_41_8_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_41_8_1' id='label_41_8_1' class='gform-field-label gform-field-label--type-inline'>He llegit i accepto la <a href=\"https:\/\/cases.fundesplai.org\/politica-de-privacitat\/\" target=\"_blank\">pol\u00edtica de privacitat<\/a><\/label>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/fieldset><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_41' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Subscriu-te per rebre el PDF'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_41' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_41' id='gform_theme_41' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_41' id='gform_style_settings_41' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_41' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='41' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='oPATe8kQcnb10h4cN8Jt6C\/n2gvPtG902az2v78FFJQu+Ztsx\/Eu8maibXl5oV2f2ZIZR\/+TZwHzHLH1LfNrAg\/t+8iqpOtPK1iHNE3PJexd108=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_41' value='WyJ7XCI4LjFcIjpcImUyYzI4YjYxNzNlN2QzMDJlZmQ1NTc2MzQwNDM1NDNjXCJ9IiwiOTNmMmEwY2NlMjFkOTY3MGJiYmU0N2IyODhhYTAzMDUiXQ==' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_41' id='gform_target_page_number_41' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_41' id='gform_source_page_number_41' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='tipus=guia-malbaratament-alimentari-cases-colonies' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 41, 'https:\/\/cases.fundesplai.org\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_41').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_41');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_41').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_41').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_41').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_41').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_41').val();gformInitSpinner( 41, 'https:\/\/cases.fundesplai.org\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [41, current_page]);window['gf_submitting_41'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_41').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [41]);window['gf_submitting_41'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_41').text());}else{jQuery('#gform_41').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"41\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_41\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_41\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_41\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 41, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbAltres recursos\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>OTROS RECURSOS SOBRE DESARROLLO ALIMENTARIO<\/h3>\n<ul>\n<li><a href=\"https:\/\/cases.fundesplai.org\/es\/blog-es\/familia-es\/6-ideas-para-reducir-el-desperdicio-alimentario-desde-casa\/\">6 ideas para reducir el desperdicio alimentario desde casa<\/a><\/li>\n<li><a href=\"https:\/\/menjaactuaimpacta.org\/es\/blog-es\/eat-life-9-propuestas-clave-para-reducir-el-desperdicio-alimentario\/\">9 propuestas clave para reducir el desperdicio alimentario<\/a><\/li>\n<li><a href=\"https:\/\/menjaactuaimpacta.org\/es\/blog-es\/eat-life-el-coste-de-los-alimentos-que-se-desperdician\/\">El coste de los alimentos que se desperdician<\/a><\/li>\n<li><a href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/recursos-educativos-para-reducir-el-desperdicio-alimentarios\/\">Recursos educativos para reducir el desperdicio alimentario<\/a><\/li>\n<li><a href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/comedor-escolar\/5-actividades-sobre-el-desperdicio-alimentario\/\">5 actividades contra el derroche alimentario<\/a><\/li>\n<li><a href=\"https:\/\/residus.gencat.cat\/es\/ambits_dactuacio\/prevencio\/malbaratament_alimentari\/recursos\/index.html\">Recursos de la Generalitat de Catalu\u00f1a sobre el desperdicio alimentario<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbXXSS\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong>Si te ha gustado esta entrada, \u00a1comp\u00e1rtela en las redes sociales! \ud83d\ude09<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/cases.fundesplai.org\/es\/alojamientos\/\u00bb button_text=\u00bb\u00a1Descubre nuestras casas de colonias y terrenos de acampada!\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubre nuestra gu\u00eda educativa para reducir el desperdicio alimentario en las casas de colonias y hacer part\u00edcipes a los ni\u00f1os y ni\u00f1as de todo el proceso. <\/p>\n","protected":false},"author":426,"featured_media":59816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[359],"tags":[],"class_list":["post-59860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colonias-y-campamentos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo reducimos el desperdicio alimentario en las casas de colonias - Cases de col\u00f2nies - Fundesplai<\/title>\n<meta name=\"description\" content=\"Descubre la gu\u00eda educativa para reducir el desperdicio alimentario en las casas de colonias y hacer part\u00edcipes a los ni\u00f1os y ni\u00f1as de todo el proceso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo reducimos el desperdicio alimentario en las casas de colonias - Cases de col\u00f2nies - Fundesplai\" \/>\n<meta property=\"og:description\" content=\"Descubre la gu\u00eda educativa para reducir el desperdicio alimentario en las casas de colonias y hacer part\u00edcipes a los ni\u00f1os y ni\u00f1as de todo el proceso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/\" \/>\n<meta property=\"og:site_name\" content=\"Cases de col\u00f2nies - Fundesplai\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-12T14:39:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T10:36:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/09\/Com-reduir-malbaratament-alimentari-cases.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"anna.maestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anna.maestre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/\"},\"author\":{\"name\":\"anna.maestre\",\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/abd686cee7b927c9c77c1a706d05a410\"},\"headline\":\"C\u00f3mo reducimos el desperdicio alimentario en las casas de colonias\",\"datePublished\":\"2025-09-12T14:39:53+00:00\",\"dateModified\":\"2025-09-15T10:36:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/\"},\"wordCount\":1611,\"image\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cases.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Com-reduir-malbaratament-alimentari-cases.webp\",\"articleSection\":[\"Colonias y campamentos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/\",\"url\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/\",\"name\":\"C\u00f3mo reducimos el desperdicio alimentario en las casas de colonias - Cases de col\u00f2nies - Fundesplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cases.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Com-reduir-malbaratament-alimentari-cases.webp\",\"datePublished\":\"2025-09-12T14:39:53+00:00\",\"dateModified\":\"2025-09-15T10:36:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/abd686cee7b927c9c77c1a706d05a410\"},\"description\":\"Descubre la gu\u00eda educativa para reducir el desperdicio alimentario en las casas de colonias y hacer part\u00edcipes a los ni\u00f1os y ni\u00f1as de todo el proceso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cases.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Com-reduir-malbaratament-alimentari-cases.webp\",\"contentUrl\":\"https:\\\/\\\/cases.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Com-reduir-malbaratament-alimentari-cases.webp\",\"width\":1888,\"height\":900,\"caption\":\"M\u00e0 de persona tirant restes de brossa a les escombraries (malbaratament alimentari)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/blog-es\\\/colonias-y-campamentos\\\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/inici-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo reducimos el desperdicio alimentario en las casas de colonias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/\",\"name\":\"Cases de col\u00f2nies - Fundesplai\",\"description\":\"Equipaments de Fundesplai\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/abd686cee7b927c9c77c1a706d05a410\",\"name\":\"anna.maestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af546adb88acc5f028b261824053a416adc3c7e35823e779929de3c9bc1e508b?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af546adb88acc5f028b261824053a416adc3c7e35823e779929de3c9bc1e508b?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af546adb88acc5f028b261824053a416adc3c7e35823e779929de3c9bc1e508b?s=96&d=identicon&r=g\",\"caption\":\"anna.maestre\"},\"url\":\"https:\\\/\\\/cases.fundesplai.org\\\/es\\\/author\\\/anna-maestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo reducimos el desperdicio alimentario en las casas de colonias - Cases de col\u00f2nies - Fundesplai","description":"Descubre la gu\u00eda educativa para reducir el desperdicio alimentario en las casas de colonias y hacer part\u00edcipes a los ni\u00f1os y ni\u00f1as de todo el proceso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo reducimos el desperdicio alimentario en las casas de colonias - Cases de col\u00f2nies - Fundesplai","og_description":"Descubre la gu\u00eda educativa para reducir el desperdicio alimentario en las casas de colonias y hacer part\u00edcipes a los ni\u00f1os y ni\u00f1as de todo el proceso.","og_url":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/","og_site_name":"Cases de col\u00f2nies - Fundesplai","article_published_time":"2025-09-12T14:39:53+00:00","article_modified_time":"2025-09-15T10:36:20+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/09\/Com-reduir-malbaratament-alimentari-cases.webp","type":"image\/webp"}],"author":"anna.maestre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"anna.maestre","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/#article","isPartOf":{"@id":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/"},"author":{"name":"anna.maestre","@id":"https:\/\/cases.fundesplai.org\/es\/#\/schema\/person\/abd686cee7b927c9c77c1a706d05a410"},"headline":"C\u00f3mo reducimos el desperdicio alimentario en las casas de colonias","datePublished":"2025-09-12T14:39:53+00:00","dateModified":"2025-09-15T10:36:20+00:00","mainEntityOfPage":{"@id":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/"},"wordCount":1611,"image":{"@id":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/#primaryimage"},"thumbnailUrl":"https:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/09\/Com-reduir-malbaratament-alimentari-cases.webp","articleSection":["Colonias y campamentos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/","url":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/","name":"C\u00f3mo reducimos el desperdicio alimentario en las casas de colonias - Cases de col\u00f2nies - Fundesplai","isPartOf":{"@id":"https:\/\/cases.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/#primaryimage"},"image":{"@id":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/#primaryimage"},"thumbnailUrl":"https:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/09\/Com-reduir-malbaratament-alimentari-cases.webp","datePublished":"2025-09-12T14:39:53+00:00","dateModified":"2025-09-15T10:36:20+00:00","author":{"@id":"https:\/\/cases.fundesplai.org\/es\/#\/schema\/person\/abd686cee7b927c9c77c1a706d05a410"},"description":"Descubre la gu\u00eda educativa para reducir el desperdicio alimentario en las casas de colonias y hacer part\u00edcipes a los ni\u00f1os y ni\u00f1as de todo el proceso.","breadcrumb":{"@id":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/#primaryimage","url":"https:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/09\/Com-reduir-malbaratament-alimentari-cases.webp","contentUrl":"https:\/\/cases.fundesplai.org\/wp-content\/uploads\/2025\/09\/Com-reduir-malbaratament-alimentari-cases.webp","width":1888,"height":900,"caption":"M\u00e0 de persona tirant restes de brossa a les escombraries (malbaratament alimentari)"},{"@type":"BreadcrumbList","@id":"https:\/\/cases.fundesplai.org\/es\/blog-es\/colonias-y-campamentos\/como-reducimos-el-desperdicio-alimentario-en-las-casas-de-colonias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/cases.fundesplai.org\/es\/inici-2\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo reducimos el desperdicio alimentario en las casas de colonias"}]},{"@type":"WebSite","@id":"https:\/\/cases.fundesplai.org\/es\/#website","url":"https:\/\/cases.fundesplai.org\/es\/","name":"Cases de col\u00f2nies - Fundesplai","description":"Equipaments de Fundesplai","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cases.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/cases.fundesplai.org\/es\/#\/schema\/person\/abd686cee7b927c9c77c1a706d05a410","name":"anna.maestre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/af546adb88acc5f028b261824053a416adc3c7e35823e779929de3c9bc1e508b?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af546adb88acc5f028b261824053a416adc3c7e35823e779929de3c9bc1e508b?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af546adb88acc5f028b261824053a416adc3c7e35823e779929de3c9bc1e508b?s=96&d=identicon&r=g","caption":"anna.maestre"},"url":"https:\/\/cases.fundesplai.org\/es\/author\/anna-maestre\/"}]}},"_links":{"self":[{"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/59860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/426"}],"replies":[{"embeddable":true,"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=59860"}],"version-history":[{"count":19,"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/59860\/revisions"}],"predecessor-version":[{"id":59957,"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/59860\/revisions\/59957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/59816"}],"wp:attachment":[{"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=59860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=59860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cases.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=59860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}